{"id":11593,"date":"2026-07-01T22:18:55","date_gmt":"2026-07-01T22:18:55","guid":{"rendered":"https:\/\/costless.website\/?page_id=11593"},"modified":"2026-08-14T21:33:38","modified_gmt":"2026-08-14T21:33:38","slug":"baofeng-uv-5r-thank-you-page","status":"publish","type":"page","link":"https:\/\/costless.website\/index.php\/baofeng-uv-5r-thank-you-page\/","title":{"rendered":"BAOFENG UV-5R THANK YOU PAGE"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"11593\" class=\"elementor elementor-11593\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef2d5f5 e-flex e-con-boxed e-con e-parent\" data-id=\"ef2d5f5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b98c0e0 elementor-widget elementor-widget-html\" data-id=\"b98c0e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- Meta Pixel Code -->\r\n<script>\r\n!function(f,b,e,v,n,t,s)\r\n{if(f.fbq)return;n=f.fbq=function(){n.callMethod?\r\nn.callMethod.apply(n,arguments):n.queue.push(arguments)};\r\nif(!f._fbq)f._fbq=n;n.push=n;n.loaded=!0;n.version='2.0';\r\nn.queue=[];t=b.createElement(e);t.async=!0;\r\nt.src=v;s=b.getElementsByTagName(e)[0];\r\ns.parentNode.insertBefore(t,s)}(window, document,'script',\r\n'https:\/\/connect.facebook.net\/en_US\/fbevents.js');\r\nfbq('init', '629738149249652');\r\nfbq('track', 'PageView');\r\n<\/script>\r\n<noscript><img height=\"1\" width=\"1\" style=\"display:none\"\r\nsrc=\"https:\/\/www.facebook.com\/tr?id=629738149249652&ev=PageView&noscript=1\"\r\n\/><\/noscript>\r\n<!-- End Meta Pixel Code -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b372fa6 elementor-widget elementor-widget-heading\" data-id=\"b372fa6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">THANK YOU<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-883c712 elementor-widget elementor-widget-heading\" data-id=\"883c712\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">YOUR ORDER WAS SUCCESSFUL!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ee1684 elementor-widget elementor-widget-image\" data-id=\"2ee1684\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/basecafrica.com\/cdn\/shop\/products\/UV-5R-Dual-Band-UHF-VHF-Radio-6828892_1_1024x.webp?v=1781804052\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-992e326 elementor-widget elementor-widget-heading\" data-id=\"992e326\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HELP LINE: 09023858889<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>THANK YOU YOUR ORDER WAS SUCCESSFUL! HELP LINE: 09023858889<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-11593","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/costless.website\/index.php\/wp-json\/wp\/v2\/pages\/11593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costless.website\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/costless.website\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/costless.website\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/costless.website\/index.php\/wp-json\/wp\/v2\/comments?post=11593"}],"version-history":[{"count":28,"href":"https:\/\/costless.website\/index.php\/wp-json\/wp\/v2\/pages\/11593\/revisions"}],"predecessor-version":[{"id":12714,"href":"https:\/\/costless.website\/index.php\/wp-json\/wp\/v2\/pages\/11593\/revisions\/12714"}],"wp:attachment":[{"href":"https:\/\/costless.website\/index.php\/wp-json\/wp\/v2\/media?parent=11593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}